{"id":1383,"date":"2015-11-05T08:35:22","date_gmt":"2015-11-05T07:35:22","guid":{"rendered":"http:\/\/www.gewandfantasien.de\/bloggen\/?p=1383"},"modified":"2015-11-30T08:57:26","modified_gmt":"2015-11-30T07:57:26","slug":"fuer-2016-messe-und-preisanpassung","status":"publish","type":"post","link":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/","title":{"rendered":"F\u00fcr 2016: Messe und Preisanpassung"},"content":{"rendered":"<h3>Wohin f\u00fchrt der Weg 2016 eigentlich?<\/h3>\n<p>In den letzten Wochen und Monaten haben sich so einige Weichen neu gestellt. Zun\u00e4chst einmal die gute Nachricht: Das hier wird kein Abschiedspost, ganz im Gegenteil! Und die Ver\u00e4nderungen sind auch &#8211; hoffe ich mal &#8211; alle zum Guten bzw. Besseren. Denn \u00fcber 2015 kann ich in Bezug auf Gewandfantasien echt nicht klagen. Daf\u00fcr erstmal ein ganz dickes DANKE an dich, euch, jeden da drau\u00dfen. F\u00fcr Auftr\u00e4ge oder einfach &#8222;nur&#8220; Unterst\u00fctzung.<\/p>\n<p>Trotzdem, in 2016 wird es einige \u00c4nderungen geben.<\/p>\n<h3>Gewandfantasien zieht um<\/h3>\n<p>Und zwar ganz k\u00f6rperlich. Wenn du mir bei Facebook folgst, hast du es schon gesehen. Wir bauen und hoffen mal, damit Ende Februar\/Anfang M\u00e4rz 2016 fertig zu sein. Dann werden wir nicht mehr direkt in Hamburg wohnen und damit ist Gewandfantasien dann auch nicht mehr einfach mit dem \u00f6ffentlichen Nahverkehr erreichbar (nach vorherigem Termin nat\u00fcrlich). Daf\u00fcr haben wir in Zukunft kein Problem mehr mit Parkpl\u00e4tzen. Und ich werde viel mehr Platz haben. Z.B. f\u00fcr mehr Lagerhaltung an Stoffen und damit dann auch mal g\u00fcnstige Angebote. Derzeit ist das eher schwierig, mal ein paar Stoffrollen zu lagern. Und Lagerraum in Hamburg ist ja leider auch nicht gerade g\u00fcnstig. Dr\u00fcck mir bitte die Daumen, dass alles klappt \ud83d\ude42<\/p>\n<div class=\"wc-gallery\"><div id='gallery-1' data-gutter-width='5' data-columns='3' class='gallery wc-gallery-captions-onhover gallery-link-file gallery-masonry galleryid-1383 gallery-columns-3 gallery-size-thumbnail wc-gallery-bottomspace-default wc-gallery-clear'><div class='gallery-item gallery-item-position-1 gallery-item-attachment-1385'>\n\t\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-1-750x500.jpg' title='Unser Rohbau' target='_self'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Unser Haus, derzeit noch im Rohbau\" srcset=\"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-1-150x150.jpg 150w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-1-300x300.jpg 300w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<div class='wp-caption-text gallery-caption'>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\tUnser Haus, derzeit noch im Rohbau\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div><\/div><div class='gallery-item gallery-item-position-2 gallery-item-attachment-1386'>\n\t\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-23-750x500.jpg' title='Mein k\u00fcnftiger Arbeitsplatz' target='_self'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Gewandfantasiens zuk\u00fcnftiges Atelier\" srcset=\"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-23-150x150.jpg 150w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-23-300x300.jpg 300w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/drempel-23-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<div class='wp-caption-text gallery-caption'>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\tGewandfantasiens zuk\u00fcnftiges Atelier\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div><\/div><\/div>\n<\/div>\n<h3>Dank Umzug: ein kleiner Sale<\/h3>\n<p>Du kennst das bestimmt auch. Umziehen m\u00f6chte man ja mit m\u00f6glichst wenig. Daher gibt es aktuell alle fertigen Kleider, M\u00e4ntel, Kost\u00fcme etc. zu teilweise deutlich reduzierten Preisen. Aber nur hier im eigenen Shop!<\/p>\n<p><a href=\"http:\/\/www.gewandfantasien.de\/sofort-lieferbar\/\" target=\"_blank\">Angebote im Sale<\/a><\/p>\n<h3>Gewandfantasien zum Anfassen<\/h3>\n<p>Bisher gibt es Gewandfantasien ja nur online oder bei einem Besuch hier in Hamburg. Oder wenn man sich auf einer Veranstaltung trifft. 2016 kannst du mich zusammen mit meiner Kollegin Susanne und ihren tollen Viechern aus der <a href=\"http:\/\/www.unikat-manufaktur.de\/\" target=\"_blank\">unikat-manufaktur<\/a> auch mal in natura auf einer Messe erleben. Und zwar auf der <a href=\"http:\/\/www.larpwerker-convention.de\/\" target=\"_blank\">LarpWerker Convention<\/a> am 27. Februar 2016 in Dreieich (nahe Frankfurt).<\/p>\n<p>Dort kannst du nat\u00fcrlich auch in alle mitgebrachten Kleider und Kost\u00fcme schl\u00fcpfen. Oder du l\u00e4sst direkt deine Ma\u00dfe f\u00fcr einen Auftrag nehmen. Gerne bringe ich dir auch ein bestimmtes Kleid oder Kost\u00fcm dahin mit.<\/p>\n<figure id=\"attachment_1387\" aria-describedby=\"caption-attachment-1387\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-1387\" src=\"http:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016-750x273.jpg\" alt=\"Larpwerker Convention 2016\" width=\"750\" height=\"273\" srcset=\"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016-750x273.jpg 750w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016-600x218.jpg 600w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016-300x109.jpg 300w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016-150x55.jpg 150w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016-770x280.jpg 770w, https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/larpwerker-convention-2016.jpg 940w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-1387\" class=\"wp-caption-text\">Larpwerker Convention am 27.2.2016<\/figcaption><\/figure>\n<p>Nat\u00fcrlich gibt es au\u00dfer uns beiden noch viele andere interessante Aussteller. Und das beste, alle produzieren noch selbst in Deutschland. Also keine Massenware aus Billig-Lohnl\u00e4ndern!<\/p>\n<p>Zu der Messe gibt es in den n\u00e4chsten Wochen auch noch mehr Infos.<\/p>\n<h3>Leider auch: Preisanpassung nach oben<\/h3>\n<p>Als letztes steht noch ein Punkt an, der f\u00fcr mich gleichzeitig Anlass zur Freude ist, den ich aber auch ungern mache. Ich werde 2016 viele Preise anheben m\u00fcssen.<\/p>\n<p>Ein Grund daf\u00fcr sind mal wieder steigende Materialkosten. Meine Preise sind in der Regel so knapp kalkuliert wie m\u00f6glich und die aktuellen Stoffpreise sind leider zu hoch geworden. Da der Trend hier eher weiter nach oben geht, muss ich die Preise anpassen. Aber erst nach Weihnachten!<\/p>\n<p>Der zweite, viel sch\u00f6nere Grund: Innerhalb von gerade mal 1,5 Jahren Gewandfantasien in Vollzeit haben wir es zusammen geschafft, dass Gewandfantasien kein Kleingewerbe mehr ist. Gewandfantasien ist sozusagen erwachsen geworden. Wow! Ganz herzlichen Dank nochmal an jeden von euch daf\u00fcr!<\/p>\n<p>Das hei\u00dft aber auch, dass ich vom deutschen Gesetz her ab 2016 auf alle Produkte Mehrwertsteuer aufschlagen muss. Nat\u00fcrlich, ich kann teilweise g\u00fcnstiger einkaufen aber die meisten Artikel werden unterm Strich teurer.<\/p>\n<p>Mein Ratschlag daher: wenn du schon l\u00e4nger mit einem bestimmten Kleid, Umhang, Gewandungsteil etc. lieb\u00e4ugelst, bestell es bitte noch vor Weihnachten!<\/p>\n<p>Also, es \u00e4ndert sich viel in 2016 und ich hoffe, dass nichts davon dich abschreckt!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wohin f\u00fchrt der Weg 2016 eigentlich? In den letzten Wochen und Monaten haben sich so einige Weichen neu gestellt. Zun\u00e4chst einmal die gute Nachricht: Das hier wird kein Abschiedspost, ganz im Gegenteil! Und die Ver\u00e4nderungen sind auch &#8211; hoffe ich mal &#8211; alle zum Guten bzw. Besseren. Denn \u00fcber 2015 kann ich in Bezug auf [&hellip;]<\/p>\n","protected":false},"author":754,"featured_media":1384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31],"tags":[100,99,6,101,102,34],"class_list":["post-1383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shop","tag-100","tag-aenderungen","tag-online-verkaufen","tag-preise","tag-sale","tag-shop-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr 2016: Messe und Preisanpassung - Gewandfantasien<\/title>\n<meta name=\"description\" content=\"Viel neues in 2016: Aussteller auf einer Messe, Umzug in gr\u00f6\u00dfere R\u00e4ume und Gewandfantasien wird erwachsen. Alle infos und Konsequenzen findest du im Blog\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr 2016: Messe und Preisanpassung - Gewandfantasien\" \/>\n<meta property=\"og:description\" content=\"Viel neues in 2016: Aussteller auf einer Messe, Umzug in gr\u00f6\u00dfere R\u00e4ume und Gewandfantasien wird erwachsen. Alle infos und Konsequenzen findest du im Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/\" \/>\n<meta property=\"og:site_name\" content=\"Gewandfantasien\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Gewandfantasien\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Gewandfantasien\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-05T07:35:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-30T07:57:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/Bruecke-Kloster-Hude-1-750x500.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Gewandfantasien\" \/>\n<meta name=\"twitter:site\" content=\"@Gewandfantasien\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/\"},\"author\":{\"name\":\"Andrea\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#\\\/schema\\\/person\\\/8cd6eb5a248eb136e1f30de5978e39a0\"},\"headline\":\"F\u00fcr 2016: Messe und Preisanpassung\",\"datePublished\":\"2015-11-05T07:35:22+00:00\",\"dateModified\":\"2015-11-30T07:57:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/\"},\"wordCount\":621,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Bruecke-Kloster-Hude-1.jpg\",\"keywords\":[\"2016\",\"\u00c4nderungen\",\"Online verkaufen\",\"Preise\",\"Sale\",\"Shop\"],\"articleSection\":[\"eigener Shop\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/\",\"url\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/\",\"name\":\"F\u00fcr 2016: Messe und Preisanpassung - Gewandfantasien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Bruecke-Kloster-Hude-1.jpg\",\"datePublished\":\"2015-11-05T07:35:22+00:00\",\"dateModified\":\"2015-11-30T07:57:26+00:00\",\"description\":\"Viel neues in 2016: Aussteller auf einer Messe, Umzug in gr\u00f6\u00dfere R\u00e4ume und Gewandfantasien wird erwachsen. Alle infos und Konsequenzen findest du im Blog\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Bruecke-Kloster-Hude-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Bruecke-Kloster-Hude-1.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Wohin f\u00fchrt der Weg f\u00fcr Gewandfantasien in 2016\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/2015\\\/11\\\/fuer-2016-messe-und-preisanpassung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr 2016: Messe und Preisanpassung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#website\",\"url\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/\",\"name\":\"Gewandfantasien\",\"description\":\"Dress your Fantasy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#organization\",\"name\":\"Gewandfantasien\",\"url\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_gewandfantasien_kurz.png\",\"contentUrl\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_gewandfantasien_kurz.png\",\"width\":250,\"height\":250,\"caption\":\"Gewandfantasien\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Gewandfantasien\",\"https:\\\/\\\/x.com\\\/Gewandfantasien\",\"http:\\\/\\\/instagram.com\\\/gewandfantasien\",\"http:\\\/\\\/pinterest.com\\\/gewandfantasien\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gewandfantasien.de\\\/bloggen\\\/#\\\/schema\\\/person\\\/8cd6eb5a248eb136e1f30de5978e39a0\",\"name\":\"Andrea\",\"sameAs\":[\"http:\\\/\\\/www.gewandfantasien.de\",\"https:\\\/\\\/www.facebook.com\\\/Gewandfantasien\",\"http:\\\/\\\/instagram.com\\\/gewandfantasien\",\"https:\\\/\\\/x.com\\\/Gewandfantasien\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr 2016: Messe und Preisanpassung - Gewandfantasien","description":"Viel neues in 2016: Aussteller auf einer Messe, Umzug in gr\u00f6\u00dfere R\u00e4ume und Gewandfantasien wird erwachsen. Alle infos und Konsequenzen findest du im Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr 2016: Messe und Preisanpassung - Gewandfantasien","og_description":"Viel neues in 2016: Aussteller auf einer Messe, Umzug in gr\u00f6\u00dfere R\u00e4ume und Gewandfantasien wird erwachsen. Alle infos und Konsequenzen findest du im Blog","og_url":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/","og_site_name":"Gewandfantasien","article_publisher":"https:\/\/www.facebook.com\/Gewandfantasien","article_author":"https:\/\/www.facebook.com\/Gewandfantasien","article_published_time":"2015-11-05T07:35:22+00:00","article_modified_time":"2015-11-30T07:57:26+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/Bruecke-Kloster-Hude-1-750x500.jpg","type":"image\/jpeg"}],"author":"Andrea","twitter_card":"summary_large_image","twitter_creator":"@Gewandfantasien","twitter_site":"@Gewandfantasien","twitter_misc":{"Verfasst von":"Andrea","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#article","isPartOf":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/"},"author":{"name":"Andrea","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#\/schema\/person\/8cd6eb5a248eb136e1f30de5978e39a0"},"headline":"F\u00fcr 2016: Messe und Preisanpassung","datePublished":"2015-11-05T07:35:22+00:00","dateModified":"2015-11-30T07:57:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/"},"wordCount":621,"commentCount":1,"publisher":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#organization"},"image":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/Bruecke-Kloster-Hude-1.jpg","keywords":["2016","\u00c4nderungen","Online verkaufen","Preise","Sale","Shop"],"articleSection":["eigener Shop"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/","url":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/","name":"F\u00fcr 2016: Messe und Preisanpassung - Gewandfantasien","isPartOf":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#primaryimage"},"image":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/Bruecke-Kloster-Hude-1.jpg","datePublished":"2015-11-05T07:35:22+00:00","dateModified":"2015-11-30T07:57:26+00:00","description":"Viel neues in 2016: Aussteller auf einer Messe, Umzug in gr\u00f6\u00dfere R\u00e4ume und Gewandfantasien wird erwachsen. Alle infos und Konsequenzen findest du im Blog","breadcrumb":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#primaryimage","url":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/Bruecke-Kloster-Hude-1.jpg","contentUrl":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2015\/11\/Bruecke-Kloster-Hude-1.jpg","width":2000,"height":1333,"caption":"Wohin f\u00fchrt der Weg f\u00fcr Gewandfantasien in 2016"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/2015\/11\/fuer-2016-messe-und-preisanpassung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gewandfantasien.de\/bloggen\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr 2016: Messe und Preisanpassung"}]},{"@type":"WebSite","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#website","url":"https:\/\/www.gewandfantasien.de\/bloggen\/","name":"Gewandfantasien","description":"Dress your Fantasy","publisher":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gewandfantasien.de\/bloggen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#organization","name":"Gewandfantasien","url":"https:\/\/www.gewandfantasien.de\/bloggen\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#\/schema\/logo\/image\/","url":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2018\/03\/logo_gewandfantasien_kurz.png","contentUrl":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-content\/uploads\/2018\/03\/logo_gewandfantasien_kurz.png","width":250,"height":250,"caption":"Gewandfantasien"},"image":{"@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Gewandfantasien","https:\/\/x.com\/Gewandfantasien","http:\/\/instagram.com\/gewandfantasien","http:\/\/pinterest.com\/gewandfantasien\/"]},{"@type":"Person","@id":"https:\/\/www.gewandfantasien.de\/bloggen\/#\/schema\/person\/8cd6eb5a248eb136e1f30de5978e39a0","name":"Andrea","sameAs":["http:\/\/www.gewandfantasien.de","https:\/\/www.facebook.com\/Gewandfantasien","http:\/\/instagram.com\/gewandfantasien","https:\/\/x.com\/Gewandfantasien"]}]}},"_links":{"self":[{"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/posts\/1383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/users\/754"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/comments?post=1383"}],"version-history":[{"count":4,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/posts\/1383\/revisions"}],"predecessor-version":[{"id":1445,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/posts\/1383\/revisions\/1445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/media\/1384"}],"wp:attachment":[{"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/media?parent=1383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/categories?post=1383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gewandfantasien.de\/bloggen\/wp-json\/wp\/v2\/tags?post=1383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}